{"id":123,"count":201,"description":"L'Acropora est le genre le plus diversifi\u00e9 de la famille des SPS, avec plus de 300 esp\u00e8ces pr\u00e9sentes dans les r\u00e9cifs tropicaux du monde entier.\r\nLeurs formes de croissance vont des \u00e9l\u00e9gants troncs d'arbre aux larges tables, chacun arborant des couleurs vives et des structures squelettiques complexes.\r\nNotre s\u00e9lection comprend \u00e0 la fois des vari\u00e9t\u00e9s classiques et des morphes de couleurs rares, des pourpres profonds et des bleus \u00e9lectriques aux sp\u00e9cimens multicolores avec des pointes de croissance contrast\u00e9es.","link":"https:\/\/reef-corner.com\/fr\/product-category\/corals\/sps\/acropora\/","name":"Acropora","slug":"acropora","taxonomy":"product_cat","parent":193,"meta":[],"menu_order":44,"acf":[],"_links":{"self":[{"href":"https:\/\/reef-corner.com\/fr\/wp-json\/wp\/v2\/product_cat\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reef-corner.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/reef-corner.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/reef-corner.com\/fr\/wp-json\/wp\/v2\/product_cat\/193"}],"wp:post_type":[{"href":"https:\/\/reef-corner.com\/fr\/wp-json\/wp\/v2\/product?product_cat=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}